{"id":1358,"date":"2025-05-07T16:17:28","date_gmt":"2025-05-07T14:17:28","guid":{"rendered":"https:\/\/dancetravelling.com\/?page_id=1358"},"modified":"2026-03-26T17:33:05","modified_gmt":"2026-03-26T16:33:05","slug":"cuba-habana-santiago","status":"publish","type":"page","link":"https:\/\/dancetravelling.com\/it\/cuba-habana-santiago\/","title":{"rendered":"Cuba: da L'Avana a Santiago"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"1358\" class=\"elementor elementor-1358\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-703c51bb elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"703c51bb\" data-element_type=\"section\" data-e-type=\"section\" id=\"nosotros\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-184625df\" data-id=\"184625df\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ec6506b elementor-widget elementor-widget-gva_post_breadcrumb\" data-id=\"ec6506b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"gva_post_breadcrumb.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"gva-element-gva_post_breadcrumb gva-element\">   \r\n<div class=\"post-breadcrumb\">\r\n   <div class=\"custom-breadcrumb\" >\r\n            <div class=\"breadcrumb-main\">\r\n        <div class=\"container\">\r\n          <div class=\"breadcrumb-container-inner align-center\">\r\n            <h2 class=\"heading-title\">Cuba: da L'Avana a Santiago<\/h2>          <\/div>  \r\n        <\/div>   \r\n      <\/div>  \r\n   <\/div>\r\n<\/div>      \r\n\r\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-af7759c elementor-align-center elementor-widget elementor-widget-button\" data-id=\"af7759c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#info-viaje\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Richiedi maggiori informazioni sul viaggio<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9eae2f7 elementor-widget elementor-widget-gva-gallery\" data-id=\"9eae2f7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"gva-gallery.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"gva-element-gva-gallery gva-element\">\r\n<div class=\"gva-gallery-carousel swiper-slider-wrapper style-1\">\r\n\t<div class=\"swiper-content-inner\">\r\n   \t<div class=\"init-carousel-swiper swiper\" data-carousel=\"{&quot;items&quot;:3,&quot;items_lg&quot;:3,&quot;items_md&quot;:3,&quot;items_sm&quot;:2,&quot;items_xs&quot;:1,&quot;items_xx&quot;:1,&quot;effect&quot;:&quot;slide&quot;,&quot;space_between&quot;:30,&quot;loop&quot;:1,&quot;speed&quot;:1200,&quot;autoplay&quot;:1,&quot;autoplay_delay&quot;:5000,&quot;autoplay_hover&quot;:1,&quot;navigation&quot;:1,&quot;pagination&quot;:0,&quot;dynamic_bullets&quot;:0,&quot;pagination_type&quot;:&quot;bullets&quot;}\">\r\n      \t<div class=\"swiper-wrapper\">\r\n\t\t\t\t<div class=\"swiper-slide item\"><div class=\"gallery-one__single\"><div class=\"gallery-one__image\"><img decoding=\"async\" src=\"https:\/\/dancetravelling.com\/wp-content\/uploads\/2025\/05\/baila-en-cuba-damaris-1-500x500.jpg\" alt=\"\" \/><\/div><a class=\"gallery-one__photo photo-gallery\" href=\"https:\/\/dancetravelling.com\/wp-content\/uploads\/2025\/05\/baila-en-cuba-damaris-1.jpg\" data-elementor-lightbox-slideshow=\"gallery-4g5w\"><\/a><div class=\"gallery-one__content\"><div class=\"gallery-one__content-inner\"><span class=\"gallery-one__icon\"><i class=\"fas fa-plus\"><\/i><\/span><\/div><\/div><\/div><\/div><div class=\"swiper-slide item\"><div class=\"gallery-one__single\"><div class=\"gallery-one__image\"><img decoding=\"async\" src=\"https:\/\/dancetravelling.com\/wp-content\/uploads\/2025\/05\/baila-en-cuba-damaris-2-500x500.jpg\" alt=\"\" \/><\/div><a class=\"gallery-one__photo photo-gallery\" href=\"https:\/\/dancetravelling.com\/wp-content\/uploads\/2025\/05\/baila-en-cuba-damaris-2.jpg\" data-elementor-lightbox-slideshow=\"gallery-4g5w\"><\/a><div class=\"gallery-one__content\"><div class=\"gallery-one__content-inner\"><span class=\"gallery-one__icon\"><i class=\"fas fa-plus\"><\/i><\/span><\/div><\/div><\/div><\/div><div class=\"swiper-slide item\"><div class=\"gallery-one__single\"><div class=\"gallery-one__image\"><img decoding=\"async\" src=\"https:\/\/dancetravelling.com\/wp-content\/uploads\/2025\/05\/baila-en-cuba-damaris-15-500x500.jpg\" alt=\"\" \/><\/div><a class=\"gallery-one__photo photo-gallery\" href=\"https:\/\/dancetravelling.com\/wp-content\/uploads\/2025\/05\/baila-en-cuba-damaris-15.jpg\" data-elementor-lightbox-slideshow=\"gallery-4g5w\"><\/a><div class=\"gallery-one__content\"><div class=\"gallery-one__content-inner\"><span class=\"gallery-one__icon\"><i class=\"fas fa-plus\"><\/i><\/span><\/div><\/div><\/div><\/div><div class=\"swiper-slide item\"><div class=\"gallery-one__single\"><div class=\"gallery-one__image\"><img decoding=\"async\" src=\"https:\/\/dancetravelling.com\/wp-content\/uploads\/2025\/05\/baila-en-cuba-damaris-3-500x500.jpg\" alt=\"\" \/><\/div><a class=\"gallery-one__photo photo-gallery\" href=\"https:\/\/dancetravelling.com\/wp-content\/uploads\/2025\/05\/baila-en-cuba-damaris-3-rotated.jpg\" data-elementor-lightbox-slideshow=\"gallery-4g5w\"><\/a><div class=\"gallery-one__content\"><div class=\"gallery-one__content-inner\"><span class=\"gallery-one__icon\"><i class=\"fas fa-plus\"><\/i><\/span><\/div><\/div><\/div><\/div><div class=\"swiper-slide item\"><div class=\"gallery-one__single\"><div class=\"gallery-one__image\"><img decoding=\"async\" src=\"https:\/\/dancetravelling.com\/wp-content\/uploads\/2025\/05\/baila-en-cuba-damaris-4-500x500.jpg\" alt=\"\" \/><\/div><a class=\"gallery-one__photo photo-gallery\" href=\"https:\/\/dancetravelling.com\/wp-content\/uploads\/2025\/05\/baila-en-cuba-damaris-4-rotated.jpg\" data-elementor-lightbox-slideshow=\"gallery-4g5w\"><\/a><div class=\"gallery-one__content\"><div class=\"gallery-one__content-inner\"><span class=\"gallery-one__icon\"><i class=\"fas fa-plus\"><\/i><\/span><\/div><\/div><\/div><\/div><div class=\"swiper-slide item\"><div class=\"gallery-one__single\"><div class=\"gallery-one__image\"><img decoding=\"async\" src=\"https:\/\/dancetravelling.com\/wp-content\/uploads\/2025\/05\/baila-en-cuba-damaris-5-500x500.jpg\" alt=\"\" \/><\/div><a class=\"gallery-one__photo photo-gallery\" href=\"https:\/\/dancetravelling.com\/wp-content\/uploads\/2025\/05\/baila-en-cuba-damaris-5-rotated.jpg\" data-elementor-lightbox-slideshow=\"gallery-4g5w\"><\/a><div class=\"gallery-one__content\"><div class=\"gallery-one__content-inner\"><span class=\"gallery-one__icon\"><i class=\"fas fa-plus\"><\/i><\/span><\/div><\/div><\/div><\/div><div class=\"swiper-slide item\"><div class=\"gallery-one__single\"><div class=\"gallery-one__image\"><img decoding=\"async\" src=\"https:\/\/dancetravelling.com\/wp-content\/uploads\/2025\/05\/baila-en-cuba-damaris-6-500x500.jpg\" alt=\"\" \/><\/div><a class=\"gallery-one__photo photo-gallery\" href=\"https:\/\/dancetravelling.com\/wp-content\/uploads\/2025\/05\/baila-en-cuba-damaris-6.jpg\" data-elementor-lightbox-slideshow=\"gallery-4g5w\"><\/a><div class=\"gallery-one__content\"><div class=\"gallery-one__content-inner\"><span class=\"gallery-one__icon\"><i class=\"fas fa-plus\"><\/i><\/span><\/div><\/div><\/div><\/div><div class=\"swiper-slide item\"><div class=\"gallery-one__single\"><div class=\"gallery-one__image\"><img decoding=\"async\" src=\"https:\/\/dancetravelling.com\/wp-content\/uploads\/2025\/05\/baila-en-cuba-damaris-7-500x500.jpg\" alt=\"\" \/><\/div><a class=\"gallery-one__photo photo-gallery\" href=\"https:\/\/dancetravelling.com\/wp-content\/uploads\/2025\/05\/baila-en-cuba-damaris-7.jpg\" data-elementor-lightbox-slideshow=\"gallery-4g5w\"><\/a><div class=\"gallery-one__content\"><div class=\"gallery-one__content-inner\"><span class=\"gallery-one__icon\"><i class=\"fas fa-plus\"><\/i><\/span><\/div><\/div><\/div><\/div><div class=\"swiper-slide item\"><div class=\"gallery-one__single\"><div class=\"gallery-one__image\"><img decoding=\"async\" src=\"https:\/\/dancetravelling.com\/wp-content\/uploads\/2025\/05\/baila-en-cuba-damaris-8-500x500.jpg\" alt=\"\" \/><\/div><a class=\"gallery-one__photo photo-gallery\" href=\"https:\/\/dancetravelling.com\/wp-content\/uploads\/2025\/05\/baila-en-cuba-damaris-8-rotated.jpg\" data-elementor-lightbox-slideshow=\"gallery-4g5w\"><\/a><div class=\"gallery-one__content\"><div class=\"gallery-one__content-inner\"><span class=\"gallery-one__icon\"><i class=\"fas fa-plus\"><\/i><\/span><\/div><\/div><\/div><\/div><div class=\"swiper-slide item\"><div class=\"gallery-one__single\"><div class=\"gallery-one__image\"><img decoding=\"async\" src=\"https:\/\/dancetravelling.com\/wp-content\/uploads\/2025\/05\/baila-en-cuba-damaris-10-500x500.jpg\" alt=\"\" \/><\/div><a class=\"gallery-one__photo photo-gallery\" href=\"https:\/\/dancetravelling.com\/wp-content\/uploads\/2025\/05\/baila-en-cuba-damaris-10.jpg\" data-elementor-lightbox-slideshow=\"gallery-4g5w\"><\/a><div class=\"gallery-one__content\"><div class=\"gallery-one__content-inner\"><span class=\"gallery-one__icon\"><i class=\"fas fa-plus\"><\/i><\/span><\/div><\/div><\/div><\/div><div class=\"swiper-slide item\"><div class=\"gallery-one__single\"><div class=\"gallery-one__image\"><img decoding=\"async\" src=\"https:\/\/dancetravelling.com\/wp-content\/uploads\/2025\/05\/baila-en-cuba-damaris-11-500x500.jpg\" alt=\"\" \/><\/div><a class=\"gallery-one__photo photo-gallery\" href=\"https:\/\/dancetravelling.com\/wp-content\/uploads\/2025\/05\/baila-en-cuba-damaris-11-rotated.jpg\" data-elementor-lightbox-slideshow=\"gallery-4g5w\"><\/a><div class=\"gallery-one__content\"><div class=\"gallery-one__content-inner\"><span class=\"gallery-one__icon\"><i class=\"fas fa-plus\"><\/i><\/span><\/div><\/div><\/div><\/div><div class=\"swiper-slide item\"><div class=\"gallery-one__single\"><div class=\"gallery-one__image\"><img decoding=\"async\" src=\"https:\/\/dancetravelling.com\/wp-content\/uploads\/2025\/05\/baila-en-cuba-damaris-12-500x500.jpg\" alt=\"\" \/><\/div><a class=\"gallery-one__photo photo-gallery\" href=\"https:\/\/dancetravelling.com\/wp-content\/uploads\/2025\/05\/baila-en-cuba-damaris-12.jpg\" data-elementor-lightbox-slideshow=\"gallery-4g5w\"><\/a><div class=\"gallery-one__content\"><div class=\"gallery-one__content-inner\"><span class=\"gallery-one__icon\"><i class=\"fas fa-plus\"><\/i><\/span><\/div><\/div><\/div><\/div><div class=\"swiper-slide item\"><div class=\"gallery-one__single\"><div class=\"gallery-one__image\"><img decoding=\"async\" src=\"https:\/\/dancetravelling.com\/wp-content\/uploads\/2025\/05\/baila-en-cuba-damaris-14-500x500.jpg\" alt=\"\" \/><\/div><a class=\"gallery-one__photo photo-gallery\" href=\"https:\/\/dancetravelling.com\/wp-content\/uploads\/2025\/05\/baila-en-cuba-damaris-14-rotated.jpg\" data-elementor-lightbox-slideshow=\"gallery-4g5w\"><\/a><div class=\"gallery-one__content\"><div class=\"gallery-one__content-inner\"><span class=\"gallery-one__icon\"><i class=\"fas fa-plus\"><\/i><\/span><\/div><\/div><\/div><\/div><div class=\"swiper-slide item\"><div class=\"gallery-one__single\"><div class=\"gallery-one__image\"><img decoding=\"async\" src=\"https:\/\/dancetravelling.com\/wp-content\/uploads\/2025\/05\/baila-en-cuba-damaris-16-500x500.jpg\" alt=\"\" \/><\/div><a class=\"gallery-one__photo photo-gallery\" href=\"https:\/\/dancetravelling.com\/wp-content\/uploads\/2025\/05\/baila-en-cuba-damaris-16-rotated.jpg\" data-elementor-lightbox-slideshow=\"gallery-4g5w\"><\/a><div class=\"gallery-one__content\"><div class=\"gallery-one__content-inner\"><span class=\"gallery-one__icon\"><i class=\"fas fa-plus\"><\/i><\/span><\/div><\/div><\/div><\/div><div class=\"swiper-slide item\"><div class=\"gallery-one__single\"><div class=\"gallery-one__image\"><img decoding=\"async\" src=\"https:\/\/dancetravelling.com\/wp-content\/uploads\/2025\/05\/baila-en-cuba-damaris-17-500x500.jpg\" alt=\"\" \/><\/div><a class=\"gallery-one__photo photo-gallery\" href=\"https:\/\/dancetravelling.com\/wp-content\/uploads\/2025\/05\/baila-en-cuba-damaris-17-rotated.jpg\" data-elementor-lightbox-slideshow=\"gallery-4g5w\"><\/a><div class=\"gallery-one__content\"><div class=\"gallery-one__content-inner\"><span class=\"gallery-one__icon\"><i class=\"fas fa-plus\"><\/i><\/span><\/div><\/div><\/div><\/div><div class=\"swiper-slide item\"><div class=\"gallery-one__single\"><div class=\"gallery-one__image\"><img decoding=\"async\" src=\"https:\/\/dancetravelling.com\/wp-content\/uploads\/2025\/05\/baila-en-cuba-damaris-18-500x500.jpg\" alt=\"\" \/><\/div><a class=\"gallery-one__photo photo-gallery\" href=\"https:\/\/dancetravelling.com\/wp-content\/uploads\/2025\/05\/baila-en-cuba-damaris-18.jpg\" data-elementor-lightbox-slideshow=\"gallery-4g5w\"><\/a><div class=\"gallery-one__content\"><div class=\"gallery-one__content-inner\"><span class=\"gallery-one__icon\"><i class=\"fas fa-plus\"><\/i><\/span><\/div><\/div><\/div><\/div><div class=\"swiper-slide item\"><div class=\"gallery-one__single\"><div class=\"gallery-one__image\"><img decoding=\"async\" src=\"https:\/\/dancetravelling.com\/wp-content\/uploads\/2025\/05\/baila-en-cuba-damaris-19-500x500.jpg\" alt=\"\" \/><\/div><a class=\"gallery-one__photo photo-gallery\" href=\"https:\/\/dancetravelling.com\/wp-content\/uploads\/2025\/05\/baila-en-cuba-damaris-19.jpg\" data-elementor-lightbox-slideshow=\"gallery-4g5w\"><\/a><div class=\"gallery-one__content\"><div class=\"gallery-one__content-inner\"><span class=\"gallery-one__icon\"><i class=\"fas fa-plus\"><\/i><\/span><\/div><\/div><\/div><\/div><div class=\"swiper-slide item\"><div class=\"gallery-one__single\"><div class=\"gallery-one__image\"><img decoding=\"async\" src=\"https:\/\/dancetravelling.com\/wp-content\/uploads\/2025\/05\/baila-en-cuba-damaris-20-500x500.jpg\" alt=\"\" \/><\/div><a class=\"gallery-one__photo photo-gallery\" href=\"https:\/\/dancetravelling.com\/wp-content\/uploads\/2025\/05\/baila-en-cuba-damaris-20-rotated.jpg\" data-elementor-lightbox-slideshow=\"gallery-4g5w\"><\/a><div class=\"gallery-one__content\"><div class=\"gallery-one__content-inner\"><span class=\"gallery-one__icon\"><i class=\"fas fa-plus\"><\/i><\/span><\/div><\/div><\/div><\/div>\t\t\t<\/div>\r\n\t\t<\/div>\r\n\t<\/div>\r\n\t<div class=\"swiper-pagination\"><\/div>   <div class=\"swiper-nav-next\"><\/div><div class=\"swiper-nav-prev\"><\/div><\/div>\r\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3fdfcc91 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3fdfcc91\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-1e860b4e\" data-id=\"1e860b4e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-af52673 elementor-widget elementor-widget-gva-heading-block\" data-id=\"af52673\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"gva-heading-block.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"gva-element-gva-heading-block gva-element\">   <div class=\"align-left style-1 widget gsc-heading box-align-left auto-responsive\">\r\n      <div class=\"content-inner\">\r\n         \r\n                  \r\n           \r\n         \r\n                     <h1 class=\"title\">\r\n               <span>Cuba: Da L'Havana a Santiago<\/span>\r\n            <\/h1>\r\n                  \r\n         \r\n         \r\n      <\/div>\r\n   <\/div>\r\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9f1ddbf elementor-widget elementor-widget-heading\" data-id=\"9f1ddbf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Descrizione del viaggio<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-76742ee elementor-widget elementor-widget-text-editor\" data-id=\"76742ee\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p dir=\"ltr\">Preparati a vivere un <strong>un'esperienza di ballo e connessione culturale unica<\/strong> nell'anima pi\u00f9 autentica di Cuba: il suo <strong>oriente<\/strong>.Questa regione, meno turistica e pi\u00f9 genuina, \u00e8 la culla della rivoluzione, del son, del bolero e di espressioni afrodiscendenti profonde che hanno enormemente influenzato l'identit\u00e0 musicale del paese. Camminare per le sue citt\u00e0 \u00e8 sentire la storia viva in ogni angolo, in ogni sorriso, in ogni tamburo.<\/p><p dir=\"ltr\"><strong>Viaggeremo<\/strong> <strong>da L'Avana a Santiago<\/strong>. Oltre a percorrere la parte orientale del paese, potrai approfondire la radice e la cultura che circonda le danze cubane che tanto ti piacciono e inoltre avremo <strong>classi giornaliere<\/strong> con un professore\/una professoressa che ci<strong>\u00a0ti accompagner\u00e0 durante tutto il viaggio<\/strong>, e altri insegnanti locali. Si tratta quindi di un <strong>esperienza immersiva nel mondo della salsa nel suo paese d'origine<\/strong>, con altri compagni di viaggio che condividono la vostra stessa passione per la danza, in una <strong>gruppo ristretto internazionale<\/strong>\u00a0e con un <strong>coordinatore di viaggio<\/strong> che si assicurer\u00e0 che tutto vada alla perfezione.<\/p><p dir=\"ltr\">Ci incontreremo a <strong>L'Avana<\/strong>, la capital de Cuba, una ciudad de contrastes desde la Habana Vieja al Capitolio, el famoso Malec\u00f3n o la Plaza de la Revoluci\u00f3n. Aprovecharemos para disfrutar de alguno de los <strong>concerti<\/strong> che la capitale ci offra e domenica andremo al <strong>Vicolo Hamel<\/strong> dove sentiremo l'arte afro-cubana e la rumba nella loro massima espressione.<\/p><p dir=\"ltr\">Dopo ci sposteremo verso Oriente e la prima tappa che faremo sar\u00e0 <strong>Trinidad<\/strong>, citt\u00e0 coloniale dichiarata Patrimonio dell'Umanit\u00e0 dall'UNESCO dove potremo anche fare un'escursione in catamarano verso <strong>Cayo Blanco <\/strong>e godersi le sue barriere coralline.<\/p><p dir=\"ltr\">Continueremo a <strong>Camag\u00fcey<\/strong>, il cui centro storico \u00e8 anch'esso Patrimonio dell'Umanit\u00e0. \u00c8 conosciuta per i suoi tinajones, le sue piazze tranquille, la sua intensa vita culturale e i suoi artisti. Cogliamo l'occasione per visitare <strong>gruppo folkloristico<\/strong> da Camag\u00fcey e prendere alcune lezioni con loro con musica dal vivo.<\/p><p dir=\"ltr\">Di l\u00ec, proseguiremo verso\u00a0<strong>Guardalavaca<\/strong>, considerata una delle migliori spiagge di Cuba, dove vivremo una parentesi di 3 giorni di riposo tra sabbia bianca e acque cristalline.<\/p><p dir=\"ltr\">Dopo aver recuperato le forze, andremo verso <strong>Baracoa<\/strong>, che fu la prima villa fondata a Cuba e circondata dalla natura. Avremo l'opzione di fare escursioni in alcuni dei suoi parchi naturali e visitare una piantagione di cacao.<\/p><p dir=\"ltr\">Finalmente, arriveremo a <strong>Santiago<\/strong>, la capitale dell'Oriente. L\u00ec vedremo l'emblematica cattedrale e la Plaza C\u00e9spedes, con musica dal vivo ad ogni angolo. A Santiago avremo lezioni con <strong>Yanek Revilla<\/strong> dal casin\u00f2 e sono nella loro scuola, accanto alla loro compagnia.<\/p><p dir=\"ltr\">Possiamo anche approfittare degli ultimi giorni per visitare il <strong>Castello di Morro<\/strong> con vista alla baia o il <strong>Santuario Nacional de la Virgen de la Caridad del Cobre<\/strong>. Di notte potremo goderci in <strong>Casa della Trova<\/strong>, luogo dove il son fu suonato e ballato per la prima volta.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-53d48b4 elementor-widget elementor-widget-heading\" data-id=\"53d48b4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Di cosa avete bisogno per viaggiare a Cuba?<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-93c644a elementor-widget elementor-widget-text-editor\" data-id=\"93c644a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ul><li>Passaporto: Deve avere una validit\u00e0 minima di 6 mesi dalla data di ingresso nel paese.<\/li><li><b>Visto <\/b>Richiesta online a questo link\u00a0<a href=\"https:\/\/evisacuba.cu\/es\/solicitar\/visa\">https:\/\/evisacuba.cu\/es\/solicitar\/visa<\/a><\/li><li><b>Voli: <\/b>I voli internazionali non sono inclusi nel viaggio. Raccomandiamo di prenotare l'andata per L'Avana e il ritorno da Santiago.<\/li><li><b>Certificati:<\/b> \u00c8 necessario presentare un QR che deve essere emesso 48 ore prima del viaggio al seguente link\u00a0<a href=\"https:\/\/dviajeros.mitrans.gob.cu\/inicio\">https:\/\/dviajeros.mitrans.gob.cu\/inicio<\/a><\/li><\/ul><p>Per ulteriori informazioni, si consiglia di visitare il sito web del MAEC:\u00a0<a href=\"https:\/\/www.exteriores.gob.es\/es\/ServiciosAlCiudadano\/Paginas\/Detalle-recomendaciones-de-viaje.aspx?trc=Cuba\">https:\/\/www.exteriores.gob.es\/es\/ServiciosAlCiudadano\/Paginas\/Detalle-recomendaciones-de-viaje.aspx?trc=Cuba<\/a><span style=\"color: var(--e-global-color-text); font-family: var(--gowilds-font-sans-serif);\">Deve avere una validit\u00e0 minima di 6 mesi dalla data di ingresso nel paese.\u00a0<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bb32e3e elementor-widget elementor-widget-heading\" data-id=\"bb32e3e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Incontro e saluto<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9ff56bf elementor-widget elementor-widget-text-editor\" data-id=\"9ff56bf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">Questo viaggio <strong>inizia all'Avana<\/strong> y <strong>termina en<\/strong> <strong>Santiago de Cuba<\/strong>. Ci incontreremo intorno alle 20:00 il primo giorno del viaggio e l'ultimo potrai decidere quando tornare a casa (dalla mattina).<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-311f89a5 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"311f89a5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-909c910 elementor-widget elementor-widget-heading\" data-id=\"909c910\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Incluso\/Escluso<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-47a76db elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"47a76db\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">15 notti in camera condivisa<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Tutte le colazioni<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">3 giorni tutto compreso<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Trasporto privato tra le citt\u00e0<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">22 ore di lezione<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Visite a luoghi emblematici della danza<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Assistenza del coordinatore<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-times\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Voli<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-times\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Assicurazione medica e di viaggio<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-times\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Escursioni e attivit\u00e0 facoltative<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-959ebaf elementor-align-left elementor-widget elementor-widget-button\" data-id=\"959ebaf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#info-viaje\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Richiedi maggiori informazioni sul viaggio<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-68cabde elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"68cabde\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5e6d80a5 elementor-widget elementor-widget-heading\" data-id=\"5e6d80a5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Itinerario<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6c65d76 elementor-widget elementor-widget-accordion\" data-id=\"6c65d76\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"accordion.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-accordion\">\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1131\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-1131\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><i class=\"fas fa-plus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><i class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">Giorno 1: Benvenuti a Cuba!<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1131\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-1131\"><p>Ci incontreremo all'alloggio di <strong>L'Avana<\/strong> intorno alle 19-20 per condividere la nostra cena di benvenuto e, con un po' di fortuna, godere di qualche concerto che la capitale ci offrir\u00e0 e iniziare a muovere i fianchi dopo tante ore di volo \ud83d\ude42\u00a0<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1132\" class=\"elementor-tab-title\" data-tab=\"2\" role=\"button\" aria-controls=\"elementor-tab-content-1132\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><i class=\"fas fa-plus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><i class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">Giorno 2: Dal folklore cubano al Malec\u00f3n \/ Lezione di Rumba<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1132\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"2\" role=\"region\" aria-labelledby=\"elementor-tab-title-1132\"><p>Oggi avremo alla prima ora la nostra <strong>prima classe<\/strong> da ballo, e inizieremo con <strong>Rumba<\/strong>.<\/p><p>Dopo andremo al <span style=\"font-weight: bolder;\">Vicolo Hamel<\/span>, Un punto d'incontro culturale, dove ogni domenica, a partire da mezzogiorno, gruppi musicali e ballerini si esibiscono in musiche popolari come la rumba o le danze afro-cubane. Avete il coraggio di uscire e ballare?<\/p><p>Poi faremo una passeggiata sul Malec\u00f3n per andare a mangiare, e nel pomeriggio possiamo rimanere nella Habana Vieja e bere un Daiquiri nel famoso <span style=\"font-weight: bolder;\">Bar Floridita<\/span>\u00a0o un Mojito al\u00a0<span style=\"font-weight: bolder;\">Bodeguita del Medio<\/span>, o addirittura entrambi!<\/p><p>La sera, per dare il tocco finale alla prima giornata, possiamo andare a ballare all'emblematico <strong>1830<\/strong>, ti va?<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1133\" class=\"elementor-tab-title\" data-tab=\"3\" role=\"button\" aria-controls=\"elementor-tab-content-1133\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><i class=\"fas fa-plus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><i class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">Giorno 3: Alla scoperta de L'Avana \/ Lezione di Rumba<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1133\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"3\" role=\"region\" aria-labelledby=\"elementor-tab-title-1133\"><p><span style=\"font-weight: 400;\">Oggi inizieremo la giornata con il nostro <strong>CLASSE DI DANZA<\/strong>\u00a0per iniziare la giornata in movimento.<\/span><\/p><p><span style=\"color: var(--e-global-color-text); font-family: var(--gowilds-font-sans-serif);\">Poi abbiamo l'opzione di fare un <strong>tour<\/strong> per la\u00a0<\/span><span style=\"font-weight: bolder; color: var(--e-global-color-text); font-family: var(--gowilds-font-sans-serif);\">L'Avana vecchia<\/span><span style=\"color: var(--e-global-color-text); font-family: var(--gowilds-font-sans-serif);\">\u00a0con una guida locale e<\/span><span style=\"color: var(--e-global-color-text); font-family: var(--gowilds-font-sans-serif);\">\u00a0dare a <strong>passeggiata in <\/strong><\/span><span style=\"color: var(--e-global-color-text); font-family: var(--gowilds-font-sans-serif); font-weight: bolder;\">auto d'epoca<\/span><span style=\"color: var(--e-global-color-text); font-family: var(--gowilds-font-sans-serif);\">\u00a0<\/span><span style=\"color: var(--e-global-color-text); font-family: var(--gowilds-font-sans-serif);\">per L'Avana, dove passeremo per il Castello dei Tre Re del Morro, il Cristo dell'Avana o la Plaza de la Revoluci\u00f3n.<\/span><\/p><p><span style=\"color: var(--e-global-color-text); font-family: var(--gowilds-font-sans-serif);\">La sera, usciremo a ballare nel nostro ultimo\nnotte all'Avana o resteremo a riposare?<\/span><\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1134\" class=\"elementor-tab-title\" data-tab=\"4\" role=\"button\" aria-controls=\"elementor-tab-content-1134\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><i class=\"fas fa-plus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><i class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">Giorno 4: La citt\u00e0 coloniale di Trinidad<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1134\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"4\" role=\"region\" aria-labelledby=\"elementor-tab-title-1134\"><p>Oggi abbiamo un lungo viaggio verso <span style=\"font-weight: bolder;\">Trinidad<\/span>, la citt\u00e0 coloniale \u00e8 stata dichiarata\u00a0<span style=\"font-weight: bolder;\">Patrimonio mondiale dell'UNESCO<\/span>\u00a0dal 1988, grazie alla sua imponente architettura coloniale ben conservata e alla sua ricca storia.<\/p><p>All'arrivo abbiamo la possibilit\u00e0 di fare un <b>tour guidato <\/b>per la citt\u00e0. Trinidad ci sedurr\u00e0 con le sue pittoresche strade acciottolate, costellate di colorati edifici e la calda ospitalit\u00e0 cubana.<\/p><p>Dopo il tour, prenderemo un cocktail sulla terrazza dove potremo vedere il <strong>tramonto<\/strong> mentre ascoltiamo <strong>musica dal vivo<\/strong>,<span style=\"color: var(--e-global-color-text); font-family: var(--gowilds-font-sans-serif);\">\u00a0dopo cena e ballo<\/span><span style=\"color: var(--e-global-color-text); font-family: var(--gowilds-font-sans-serif); font-weight: bolder;\">\u00a0Angolo della salsa<\/span><span style=\"color: var(--e-global-color-text); font-family: var(--gowilds-font-sans-serif);\">.\u00a0<\/span><\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1135\" class=\"elementor-tab-title\" data-tab=\"5\" role=\"button\" aria-controls=\"elementor-tab-content-1135\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><i class=\"fas fa-plus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><i class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">Giorno 5: Catamarano a Cayo Blanco \/ Classe di Riparto<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1135\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"5\" role=\"region\" aria-labelledby=\"elementor-tab-title-1135\"><p><span style=\"color: var(--e-global-color-text); font-family: var(--gowilds-font-sans-serif);\">Oggi abbiamo la possibilit\u00e0 di trascorrere la giornata a<\/span><span style=\"color: var(--e-global-color-text); font-family: var(--gowilds-font-sans-serif);\">\u00a0<\/span><span style=\"color: var(--e-global-color-text); font-family: var(--gowilds-font-sans-serif); font-weight: bolder;\">Catamarano per Cayo Blanco<\/span><span style=\"color: var(--e-global-color-text); font-family: var(--gowilds-font-sans-serif);\">. Faremo una sosta per lo snorkeling e poi avremo tempo per goderci la spiaggia per circa 2 ore.<\/span><\/p><p>Nel pomeriggio, sulla via del ritorno a Trinidad, avremo il nostro\u00a0<span style=\"font-weight: bolder;\">CLASSE DI DANZA<\/span>, e di notte possiamo andare a <strong>Casa della Musica<\/strong> per ascoltare musica dal vivo e se abbiamo abbastanza energia possiamo finire nella famosa Discoteca Ayala, che si trova all'interno di una <strong>grotta<\/strong>!<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1136\" class=\"elementor-tab-title\" data-tab=\"6\" role=\"button\" aria-controls=\"elementor-tab-content-1136\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><i class=\"fas fa-plus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><i class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">Giorno 6: Camag\u00fcey, Cuba interna \/ Lezione di Afrocubano<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1136\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"6\" role=\"region\" aria-labelledby=\"elementor-tab-title-1136\"><p><span style=\"font-weight: 400;\">Oggi ci rechiamo a <strong>Camag\u00fcey<\/strong>, La citt\u00e0 dei vicoli labirintici, delle piazze coloniali e della ricchezza culturale.\u00a0<\/span><\/p><p><span style=\"font-weight: 400;\">All'arrivo pranzeremo in un paladar e faremo un <strong>lezione di afrocubano con musica dal vivo<\/strong> con il <strong>Ensemble folcloristico di Camag\u00fcey<\/strong>.<\/span><\/p><p><span style=\"font-weight: 400;\">In seguito, faremo una passeggiata nel centro storico, che \u00e8 stato dichiarato <strong>Patrimonio dell'Umanit\u00e0<\/strong>, alla scoperta delle sue strade labirintiche, delle piazze e degli emblematici tinajones.<\/span><\/p><p><span style=\"font-weight: 400;\">La sera ceneremo in un ristorante con terrazza e vedremo cosa ci riserva la notte di Camag\u00fcey.<\/span><\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1137\" class=\"elementor-tab-title\" data-tab=\"7\" role=\"button\" aria-controls=\"elementor-tab-content-1137\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><i class=\"fas fa-plus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><i class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">Giorno 7: Tradizione e tamburi a Camag\u00fcey \/ Lezione Afro-cubana<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1137\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"7\" role=\"region\" aria-labelledby=\"elementor-tab-title-1137\"><p><span style=\"font-weight: 400;\">Oggi assisteremo a un <strong>Saggio del Conjunto Folklorico di Camag\u00fcey<\/strong> e avremo la nostra <strong>Classe afro-cubana<\/strong> con musica dal vivo.<\/span><\/p><p><span style=\"font-weight: 400;\">Proseguiremo poi con un <strong>tour in bici-taxi<\/strong> per avere una visione pi\u00f9 ampia della citt\u00e0 accompagnati da una guida locale.<\/span><\/p><p><span style=\"font-weight: 400;\">Con un po' di fortuna, cercheremo anche di vedere qualche <strong>cerimonia dei tamburi yoruba<\/strong> per comprendere l'origine delle danze afrocubane che balliamo oggi.<\/span><\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1138\" class=\"elementor-tab-title\" data-tab=\"8\" role=\"button\" aria-controls=\"elementor-tab-content-1138\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><i class=\"fas fa-plus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><i class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">Giorno 8: Direzione Oriente cubano \/ Lezione Afrocubana<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1138\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"8\" role=\"region\" aria-labelledby=\"elementor-tab-title-1138\"><p><span style=\"font-weight: 400;\">Oggi ci dirigiamo gi\u00e0 verso Oriente, la cosiddetta terra calda. Lungo il cammino ci fermeremo a <strong>Holgu\u00edn<\/strong>, la terza citt\u00e0 pi\u00f9 grande del Paese, nota anche come \u201c<strong>CITT\u00c0 DEI PARCHI<\/strong>\u201dLa citt\u00e0 ha un gran numero di piazze e parchi.<\/span><\/p><p><span style=\"font-weight: 400;\">Mangeremo in un paladar tradizionale nel centro di Holgu\u00edn, per poi dirigerci verso <\/span><b>Guardalavaca<\/b><span style=\"font-weight: 400;\">, l<\/span><span style=\"color: var(--e-global-color-text); font-family: var(--gowilds-font-sans-serif);\">la zona costiera pi\u00f9 spettacolare dell'Oriente,\u00a0<\/span><span style=\"color: var(--e-global-color-text); font-family: var(--gowilds-font-sans-serif);\">Ci alloggiamo in un resort all-inclusive per i prossimi 2 giorni.<\/span><\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1139\" class=\"elementor-tab-title\" data-tab=\"9\" role=\"button\" aria-controls=\"elementor-tab-content-1139\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><i class=\"fas fa-plus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><i class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">Giorno 9: Mare e relax a Guardalavaca \/ Lezione di Afrocubano<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1139\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"9\" role=\"region\" aria-labelledby=\"elementor-tab-title-1139\"><p><span style=\"font-weight: 400;\">Oggi faremo prima la nostra <strong>CLASSE DI DANZA<\/strong>, per poi avere il resto della giornata di relax alle <strong>spiagge infinite di sabbia fine e acque cristalline<\/strong> con estese barriere coralline e abbondanti specie marine.<\/span><\/p><p><span style=\"font-weight: 400;\">Saremo in grado di scegliere tra le <strong>Spiaggia di Guardalavaca<\/strong> (pi\u00f9 vivace) o <strong>Spiaggia di smeraldo<\/strong> (pi\u00f9 silenzioso), o addirittura entrambi!\u00a0<\/span><\/p><p><span style=\"font-weight: 400;\">Oggi \u00e8 una giornata per godersi il sole, il mare e rilassarsi o forse osare fare qualche attivit\u00e0 acquatica.\u00a0<\/span><\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-11310\" class=\"elementor-tab-title\" data-tab=\"10\" role=\"button\" aria-controls=\"elementor-tab-content-11310\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><i class=\"fas fa-plus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><i class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">Giorno 10: Snorkeling, immersioni o puro relax caraibico \/ Lezione afro-cubana<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-11310\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"10\" role=\"region\" aria-labelledby=\"elementor-tab-title-11310\"><p><span style=\"font-weight: 400;\">Oggi avremo il <strong>giorno libero<\/strong> per fare quello che ci va, anche se un'opzione molto consigliata \u00e8 fare un'uscita in barca da Guardalavaca per fare <strong>boccaglio<\/strong> o <strong>immersione<\/strong> per i certificati o per chi vuole fare un battesimo.<\/span><\/p><p><span style=\"color: var(--e-global-color-text); font-family: var(--gowilds-font-sans-serif);\">Se non ti va, puoi semplicemente goderti le spiagge o semplicemente rimanere al resort a riposarti dall'ultimo giorno in paradiso.<\/span><\/p><p><span style=\"font-weight: 400;\">Concluderemo la serata con il nostro <strong>CLASSE DI DANZA<\/strong>, prima di uscire a cena e godersi gli spettacoli dell'hotel.<\/span><\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-11311\" class=\"elementor-tab-title\" data-tab=\"11\" role=\"button\" aria-controls=\"elementor-tab-content-11311\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><i class=\"fas fa-plus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><i class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">Giorno 11: Arrivo a Baracoa, dove inizi\u00f2 Cuba<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-11311\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"11\" role=\"region\" aria-labelledby=\"elementor-tab-title-11311\"><p><span style=\"font-weight: 400;\">Oggi il transfer ci verr\u00e0 a prendere presto per viaggiare fino a <strong>Baracoa<\/strong>, la prima citt\u00e0 fondata a Cuba e uno dei luoghi pi\u00f9 verdi e autentici.\u00a0<\/span><\/p><p><span style=\"font-weight: 400;\">All'arrivo, possiamo approfittare per mangiare una\u00a0<strong>aragosta<\/strong> Cubano, alla griglia, saltato con aglio e burro, in salsa creola o anche nel latte di cocco, molto tipico della zona.<\/span><\/p><p><span style=\"font-weight: 400;\">Nel pomeriggio, faremo una passeggiata nei dintorni di Baracoa per contemplare le <strong>vista della baia con la sua catena montuosa<\/strong> intorno. Passeggeremo anche lungo il Malecon e per le vie del centro con le sue case colorate, dove raramente incontreremo turisti. Potremo anche vedere la Cruz de la Parra, che \u00e8 stata lasciata da <strong>Cristoforo Colombo<\/strong> nel suo primo viaggio verso l'isola nel 1492.<\/span><\/p><p><span style=\"font-weight: 400;\">di notte possiamo goderci musica dal vivo nella <\/span><b>Casa della Trova<\/b><span style=\"font-weight: 400;\">.<\/span><\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-11312\" class=\"elementor-tab-title\" data-tab=\"12\" role=\"button\" aria-controls=\"elementor-tab-content-11312\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><i class=\"fas fa-plus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><i class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">Giorno 12: Natura e cacao a Baracoa \/ Lezione di Timba<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-11312\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"12\" role=\"region\" aria-labelledby=\"elementor-tab-title-11312\"><p><span style=\"font-weight: 400;\">Se c'\u00e8 una cosa che contraddistingue Baracoa, oltre ai suoi incredibili paesaggi, \u00e8 il suo <strong>cioccolato artigianale<\/strong>. In questa regione si coltiva cacao di alta qualit\u00e0, grazie al clima tropicale e ai terreni fertili. Il cacao di Baracoa \u00e8 100% naturale e viene esportato in tutto il mondo, soprattutto in Europa.<\/span><\/p><p><span style=\"font-weight: 400;\">Oggi abbiamo l'opzione di visitare una fattoria dove la famiglia produce cacao da diverse generazioni. Conosceremo il processo completo di <strong>produzione di cacao<\/strong> e potremo assaggiare i loro prodotti artigianali.<\/span><\/p><p><span style=\"font-weight: 400;\">Avremo quindi la possibilit\u00e0 di fare <strong>escursioni<\/strong> da alcuni dei <strong>parchi naturali<\/strong> che circonda Baracoa, oltre a fare il bagno in alcune piscine naturali. Abbiamo diverse alternative a seconda del livello fisico o del tempo che si vuole dedicare, da decidere in base al gruppo: il Canyon del fiume Yumur\u00ed, il Parco Nazionale Alejandro de Humboldt o El Yunque.<\/span><\/p><p><span style=\"font-weight: 400;\">Sulla via del ritorno a Baracoa, avremo il nostro <strong>classe<\/strong> <\/span><b>da ballo<\/b><span style=\"font-weight: 400;\">, prima di uscire a cena e prendere il nostro mojito del giorno.<\/span><\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-11313\" class=\"elementor-tab-title\" data-tab=\"13\" role=\"button\" aria-controls=\"elementor-tab-content-11313\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><i class=\"fas fa-plus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><i class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">Giorno 13: Arrivo a Santiago, la culla del son<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-11313\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"13\" role=\"region\" aria-labelledby=\"elementor-tab-title-11313\"><p>Oggi ci aspetta un lungo viaggio da Baracoa a\u00a0<strong>Santiago<\/strong><strong style=\"font-weight: 400;\">, <\/strong>la capitale dell'Oriente e anche conosciuta come la <b>Culla del Son<\/b>.<\/p><p><span style=\"color: var(--e-global-color-text); font-family: var(--gowilds-font-sans-serif);\">Nel pomeriggio si potr\u00e0 scegliere di fare una visita libera alla <\/span><strong style=\"color: var(--e-global-color-text); font-family: var(--gowilds-font-sans-serif);\">centro storico<\/strong><span style=\"color: var(--e-global-color-text); font-family: var(--gowilds-font-sans-serif);\"> oppure passeggiare a nostro piacimento dove non possiamo perdere il Parco C\u00e9spedes, la Cattedrale di Nuestra Se\u00f1ora de la Asunci\u00f3n, la Scalinata di Padre Pico e il Balcone Vel\u00e1zquez con vista sul mare.<\/span><\/p><p>Per la notte, finiremo nel\u00a0<span style=\"font-weight: bolder;\">Casa della Trova<\/span>, tempat kelahiran son, untuk mendengarkan grup musik live dan berdansa<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-11314\" class=\"elementor-tab-title\" data-tab=\"14\" role=\"button\" aria-controls=\"elementor-tab-content-11314\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><i class=\"fas fa-plus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><i class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">Giorno 14: Scoprendo il Santiago storico \/ Lezione di Son cubano<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-11314\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"14\" role=\"region\" aria-labelledby=\"elementor-tab-title-11314\"><p><span style=\"font-weight: 400;\">Oggi inizieremo la giornata con il nostro <\/span><span style=\"color: var(--e-global-color-text); font-family: var(--gowilds-font-sans-serif); font-weight: bolder;\">classe figlio,\u00a0<\/span><span style=\"color: var(--e-global-color-text); font-family: var(--gowilds-font-sans-serif);\">che non pu\u00f2 mancare nella citt\u00e0 in cui \u00e8 nato questo genere musicale, ancora oggi molto presente.<\/span><\/p><p><span style=\"color: var(--e-global-color-text); font-family: var(--gowilds-font-sans-serif);\">Dopo noi\u00a0<\/span><span style=\"color: var(--e-global-color-text); font-family: var(--gowilds-font-sans-serif);\">addentrarci nel <\/span><strong style=\"color: var(--e-global-color-text); font-family: var(--gowilds-font-sans-serif);\">anima rivoluzionaria e patrimoniale<\/strong><span style=\"color: var(--e-global-color-text); font-family: var(--gowilds-font-sans-serif);\"> di Santiago de Cuba. Visiteremo i luoghi che hanno segnato la storia del Paese, dove ogni pietra racchiude un ricordo, ogni statua ha una storia da raccontare e ogni angolo batte con forza.\u00a0<\/span><span style=\"color: var(--e-global-color-text); font-family: var(--gowilds-font-sans-serif);\">Possiamo visitare il maestoso <strong>Cimitero di Santa Ifigenia<\/strong>, luogo di riposo di grandi figure come Fidel Castro, Jos\u00e9 Mart\u00ed e Compay Segundo, e scenario dell'emozionante cambio della guardia. Possiamo anche visitare<\/span><span style=\"color: var(--e-global-color-text); font-family: var(--gowilds-font-sans-serif);\">\u00a0lui <b>Caserna Moncada<\/b>, epicentro dell'assalto guidato da Fidel Castro nel 1953 o fare una\u00a0<\/span><span style=\"color: var(--e-global-color-text); font-family: var(--gowilds-font-sans-serif);\">breve sosta nell'imponente <\/span><strong style=\"color: var(--e-global-color-text); font-family: var(--gowilds-font-sans-serif);\">Piazza della Rivoluzione<\/strong><span style=\"color: var(--e-global-color-text); font-family: var(--gowilds-font-sans-serif);\"> Antonio Maceo.<\/span><\/p><p><span style=\"font-weight: 400;\">Nel pomeriggio, ci lasceremo conquistare dal mare dall'alto della <strong>Castello di Morro<\/strong>, L'hotel \u00e8 una fortezza coloniale dichiarata Patrimonio dell'Umanit\u00e0, con una vista spettacolare sulla baia, ideale per il tramonto.<\/span><\/p><p><span style=\"color: var(--e-global-color-text); font-family: var(--gowilds-font-sans-serif);\">Di notte, t<\/span><span style=\"color: var(--e-global-color-text); font-family: var(--gowilds-font-sans-serif);\">finiremo a cena in qualche terrazza tutti insieme e se ci rimangono le forze, possiamo uscire a goderci la notte di Santiago, in posti come\u00a0<\/span><span style=\"color: var(--e-global-color-text); font-family: var(--gowilds-font-sans-serif); font-weight: bolder;\">Casa de la Trova o Casa delle Tradizioni<\/span><span style=\"color: var(--e-global-color-text); font-family: var(--gowilds-font-sans-serif);\">, per poter mettere in pratica tutto ci\u00f2 che \u00e8 stato appreso in questi giorni.<\/span><\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-11315\" class=\"elementor-tab-title\" data-tab=\"15\" role=\"button\" aria-controls=\"elementor-tab-content-11315\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><i class=\"fas fa-plus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><i class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">Giorno 15: Esplorando i dintorni di Santiago \/ Lezione di Rueda<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-11315\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"15\" role=\"region\" aria-labelledby=\"elementor-tab-title-11315\"><p><span style=\"color: var(--e-global-color-text); font-family: var(--gowilds-font-sans-serif);\">Oggi inizieremo la giornata con il nostro <b>ultima lezione di ballo<\/b>, Cosa succeder\u00e0 a <b>Rueda de Casino.<\/b><\/span><\/p><p><span style=\"color: var(--e-global-color-text); font-family: var(--gowilds-font-sans-serif);\">Poi abbiamo l'opzione di visitare alcuni luoghi nei dintorni di Santiago come:<\/span><\/p><ul><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\"><strong>Santuario nazionale della Virgen de la Caridad del Cobre:<\/strong> \u00c8 il santuario dedicato al santo patrono di Cuba, che nella religione yoruba equivale a Osh\u00fan, ed \u00e8 quindi un santuario molto visitato dai devoti di entrambe le religioni. \u00c8 il simbolo dell'unione tra religioso e popolare, un luogo carico di emozioni e sincretismo, dove si mescolano offerte, promesse e devozione, oltre a trovarsi in un bellissimo ambiente naturale.<\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\"><strong>La Grande Pietra:<\/strong> Si tratta di un'imponente roccia vulcanica a 1225 metri di altezza nella Sierra Maestra. Da qui si apre uno dei panorami pi\u00f9 spettacolari di tutta Cuba orientale, ma tenete presente che per arrivare in cima bisogna salire pi\u00f9 di 400 gradini.<\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\"><strong>Spiaggia di Siboney<\/strong>Una spiaggia locale, semplice e piena di autenticit\u00e0. Pu\u00f2 essere un buon momento per rilassarsi, mojito alla mano, con la brezza caraibica che accarezza il corpo.\u00a0<\/span><\/li><\/ul><p><span style=\"font-weight: 400;\">La decisione di andare in un posto o in un altro, dipender\u00e0 dal gruppo, a seconda di come preferir\u00e0 passare l'ultimo giorno del viaggio.<\/span><\/p><p><span style=\"color: var(--e-global-color-text); font-family: var(--gowilds-font-sans-serif);\">Al ritorno ci daremo<\/span><span style=\"color: var(--e-global-color-text); font-family: var(--gowilds-font-sans-serif);\">\u00a0un'ultima passeggiata per il <\/span><span style=\"color: var(--e-global-color-text); font-family: var(--gowilds-font-sans-serif); font-weight: bolder;\">Parco Alameda<\/span><span style=\"color: var(--e-global-color-text); font-family: var(--gowilds-font-sans-serif);\">, dove ci attende la nostra foto di gruppo nelle lettere della\u00a0<\/span><span style=\"color: var(--e-global-color-text); font-family: var(--gowilds-font-sans-serif); font-weight: bolder;\">CUBA<\/span><span style=\"color: var(--e-global-color-text); font-family: var(--gowilds-font-sans-serif);\">Un ricordo simbolico di questa esperienza condivisa.\u00a0<\/span><\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-11316\" class=\"elementor-tab-title\" data-tab=\"16\" role=\"button\" aria-controls=\"elementor-tab-content-11316\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><i class=\"fas fa-plus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><i class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">16\u00b0 giorno: Addio, Cuba<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-11316\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"16\" role=\"region\" aria-labelledby=\"elementor-tab-title-11316\"><p><span style=\"font-weight: 400;\">\u00c8 tempo di dire addio. Portiamo con noi ricordi, musica e tanto legame nei nostri cuori.\u00a0<\/span><\/p><p><span style=\"font-weight: 400;\">Ci auguriamo che il viaggio sia stato piacevole e vi diamo appuntamento alla prossima avventura con <strong>Danza in viaggio<\/strong>!<\/span><\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8359baa elementor-widget elementor-widget-heading\" data-id=\"8359baa\" data-element_type=\"widget\" data-e-type=\"widget\" id=\"info-viaje\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Richiedi maggiori informazioni<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-65397732 elementor-widget elementor-widget-shortcode\" data-id=\"65397732\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\">\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f444-o1\" lang=\"en-US\" dir=\"ltr\" data-wpcf7-id=\"444\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/it\/wp-json\/wp\/v2\/pages\/1358#wpcf7-f444-o1\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"Contact form\" novalidate=\"novalidate\" data-status=\"init\" data-trp-original-action=\"\/it\/wp-json\/wp\/v2\/pages\/1358#wpcf7-f444-o1\">\n<fieldset class=\"hidden-fields-container\"><input type=\"hidden\" name=\"_wpcf7\" value=\"444\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1.5\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"en_US\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f444-o1\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/>\n<\/fieldset>\n<div class=\"row\">\n   <div class=\"col-sm-6 col-xs-12\">\n     <span class=\"wpcf7-form-control-wrap\" data-name=\"your-name\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Nome\" value=\"\" type=\"text\" name=\"your-name\" \/><\/span>\n   <\/div>\n   <div class=\"col-sm-6 col-xs-12\">\n     <span class=\"wpcf7-form-control-wrap\" data-name=\"your-email\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Email\" value=\"\" type=\"email\" name=\"your-email\" \/><\/span>\n   <\/div>\n<\/div>\n<div class=\"row\">\n   <div class=\"col-sm-6 col-xs-12\">\n      <span class=\"wpcf7-form-control-wrap\" data-name=\"tel-671\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-tel wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-tel\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Telefono\" value=\"\" type=\"tel\" name=\"tel-671\" \/><\/span>\n   <\/div>\n   <div class=\"col-sm-6 col-xs-12\">\n      <span class=\"wpcf7-form-control-wrap\" data-name=\"your-subject\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text\" aria-invalid=\"false\" placeholder=\"A quale viaggio siete interessati?\" value=\"\" type=\"text\" name=\"your-subject\" \/><\/span>\n   <\/div>\n<\/div>\n<div class=\"row\">\n   <div class=\"col-sm-12 col-xs-12\">\n      <span class=\"wpcf7-form-control-wrap\" data-name=\"your-message\"><textarea cols=\"40\" rows=\"10\" maxlength=\"2000\" class=\"wpcf7-form-control wpcf7-textarea\" aria-invalid=\"false\" placeholder=\"Cosa vorresti sapere del viaggio?\" name=\"your-message\"><\/textarea><\/span>\n   <\/div>\n   <div class=\"col-sm-12 col-xs-12 action text-left\"><span class=\"form-action\"><input class=\"wpcf7-form-control wpcf7-submit has-spinner\" type=\"submit\" value=\"Inviare\" \/><\/span><\/div>\n<\/div><input type=\"hidden\" id=\"ct_checkjs_cf7_2ab56412b1163ee131e1246da0955bd1\" name=\"ct_checkjs_cf7\" value=\"0\" \/><script >setTimeout(function(){var ct_input_name = \"ct_checkjs_cf7_2ab56412b1163ee131e1246da0955bd1\";if (document.getElementById(ct_input_name) !== null) {var ct_input_value = document.getElementById(ct_input_name).value;document.getElementById(ct_input_name).value = document.getElementById(ct_input_name).value.replace(ct_input_value, 'd47cf856e43ad0beb36c2b72ce7a9edd848405d26fc87a08faba0986c09f23a0');}}, 1000);<\/script><input\n                    class=\"apbct_special_field apbct_email_id__wp_contact_form_7\"\n                    name=\"apbct__email_id__wp_contact_form_7\"\n                    aria-label=\"apbct__label_id__wp_contact_form_7\"\n                    type=\"text\" size=\"30\" maxlength=\"200\" autocomplete=\"off\"\n                    value=\"\"\n                \/><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<input\n                    class=\"apbct_special_field apbct_email_id__elementor_form\"\n                    name=\"apbct__email_id__elementor_form\"\n                    aria-label=\"apbct__label_id__elementor_form\"\n                    type=\"text\" size=\"30\" maxlength=\"200\" autocomplete=\"off\"\n                    value=\"\"\n                \/><input type=\"hidden\" name=\"trp-form-language\" value=\"it\"\/><\/form>\n<\/div>\n<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-ccb9bc1\" data-id=\"ccb9bc1\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-7be5c604 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7be5c604\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-1da9d40f\" data-id=\"1da9d40f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-196a8502 elementor-widget elementor-widget-gva-heading-block\" data-id=\"196a8502\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"gva-heading-block.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"gva-element-gva-heading-block gva-element\">   <div class=\"align-left style-1 widget gsc-heading box-align-left auto-responsive\">\r\n      <div class=\"content-inner\">\r\n         \r\n                  \r\n           \r\n         \r\n                     <h2 class=\"title\">\r\n               <span>Informazioni<\/span>\r\n            <\/h2>\r\n                  \r\n         \r\n         \r\n      <\/div>\r\n   <\/div>\r\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7fa4f7ee elementor-position-inline-start elementor-view-default elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"7fa4f7ee\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"flaticon-calendar\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tDate\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tDa confermare\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-201b4052 elementor-position-inline-start elementor-view-default elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"201b4052\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"flaticon-leadership\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tLe classi\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\t22 ore di lezioni di rumba, afro-cubano, son, timba, rueda e reparto\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-dd93219 elementor-position-inline-start elementor-view-default elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"dd93219\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"las la-certificate\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tLivello\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tIntermedio\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7ef46767 elementor-position-inline-start elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-view-default elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"7ef46767\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"las la-chalkboard-teacher\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tDocente senior\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tKarelia Despaigne\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-18eb17af elementor-position-inline-start elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-view-default elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"18eb17af\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"las la-clipboard\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tInsegnanti di scuola secondaria\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tFolkl\u00f3rico de Camag\u00fcey &amp; Yanek Revilla\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-69007bf8 elementor-position-inline-start elementor-view-default elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"69007bf8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"las la-user-friends\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tNumero di posti\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\t15\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-54314b11 elementor-position-inline-start elementor-view-default elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"54314b11\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"flaticon-maternity\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tEt\u00e0 minima\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\t18 anni\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-511d4557 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"511d4557\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-3004b06d\" data-id=\"3004b06d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-df49903 elementor-widget elementor-widget-gva-heading-block\" data-id=\"df49903\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"gva-heading-block.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"gva-element-gva-heading-block gva-element\">   <div class=\"align-left style-1 widget gsc-heading box-align-left auto-responsive\">\r\n      <div class=\"content-inner\">\r\n         \r\n                  \r\n           \r\n         \r\n                     <h2 class=\"title\">\r\n               <span>Condizioni di pagamento<\/span>\r\n            <\/h2>\r\n                  \r\n         \r\n         \r\n      <\/div>\r\n   <\/div>\r\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4ecb0985 elementor-position-inline-start elementor-view-default elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"4ecb0985\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"gwflaticon-best-price\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tPrezzo\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tDa confermare\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1bbe7336 elementor-position-inline-start elementor-view-default elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"1bbe7336\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"las la-money-bill-wave\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tPagamenti\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\t<span>Prenotazione: 300 \u20ac.<\/span><br><span>Rimanente in 2 rate:&nbsp;<\/span>\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5714cb8e elementor-position-inline-start elementor-view-default elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"5714cb8e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"la la-bank\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tConto corrente bancario\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tNome: Silvia Segales\n<br>IBAN: ES22 2100 0809 6102 0129 0427\n<br>Concetto: nome e cognome e viaggio\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bbb4989 elementor-align-left elementor-widget elementor-widget-button\" data-id=\"bbb4989\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#info-viaje\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Richiedi maggiori informazioni sul viaggio<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Cuba: De La Habana a Santiago Solicitar m\u00e1s informaci\u00f3n del viaje Cuba: De la Habana a Santiago Descripci\u00f3n del viaje Prep\u00e1rate para vivir una experiencia de baile y conexi\u00f3n cultural [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1428,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-1358","page","type-page","status-publish","has-post-thumbnail","hentry"],"aioseo_notices":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Cuba: De La Habana a Santiago - Dance Travelling<\/title>\n<meta name=\"description\" content=\"Dance Travelling: descubre viajes culturales guiados por la pasi\u00f3n por el baile. Sum\u00e9rgete en ritmos latinos como salsa o bachata, aprende con maestros locales, explora destinos aut\u00e9nticos y vive momentos que mueven el alma.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dancetravelling.com\/it\/cuba-habana-santiago\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cuba: De La Habana a Santiago - Dance Travelling\" \/>\n<meta property=\"og:description\" content=\"Dance Travelling: descubre viajes culturales guiados por la pasi\u00f3n por el baile. Sum\u00e9rgete en ritmos latinos como salsa o bachata, aprende con maestros locales, explora destinos aut\u00e9nticos y vive momentos que mueven el alma.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dancetravelling.com\/it\/cuba-habana-santiago\/\" \/>\n<meta property=\"og:site_name\" content=\"Dance Travelling\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-26T16:33:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dancetravelling.com\/wp-content\/uploads\/2025\/05\/dance-travelling-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"721\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"16 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dancetravelling.com\\\/cuba-habana-santiago\\\/\",\"url\":\"https:\\\/\\\/dancetravelling.com\\\/cuba-habana-santiago\\\/\",\"name\":\"Cuba: De La Habana a Santiago - Dance Travelling\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dancetravelling.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/dancetravelling.com\\\/cuba-habana-santiago\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/dancetravelling.com\\\/cuba-habana-santiago\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dancetravelling.com\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/dance-travelling-1.jpg\",\"datePublished\":\"2025-05-07T14:17:28+00:00\",\"dateModified\":\"2026-03-26T16:33:05+00:00\",\"description\":\"Dance Travelling: descubre viajes culturales guiados por la pasi\u00f3n por el baile. Sum\u00e9rgete en ritmos latinos como salsa o bachata, aprende con maestros locales, explora destinos aut\u00e9nticos y vive momentos que mueven el alma.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dancetravelling.com\\\/cuba-habana-santiago\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dancetravelling.com\\\/cuba-habana-santiago\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/dancetravelling.com\\\/cuba-habana-santiago\\\/#primaryimage\",\"url\":\"https:\\\/\\\/dancetravelling.com\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/dance-travelling-1.jpg\",\"contentUrl\":\"https:\\\/\\\/dancetravelling.com\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/dance-travelling-1.jpg\",\"width\":1080,\"height\":721,\"caption\":\"M\u00fasicos tocando en Santiago: la cuna del son\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dancetravelling.com\\\/cuba-habana-santiago\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/dancetravelling.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cuba: De La Habana a Santiago\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dancetravelling.com\\\/#website\",\"url\":\"https:\\\/\\\/dancetravelling.com\\\/\",\"name\":\"Dance Travelling\",\"description\":\"Baila y viaja en Cuba\",\"publisher\":{\"@id\":\"https:\\\/\\\/dancetravelling.com\\\/#organization\"},\"alternateName\":\"Dance Travelling\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dancetravelling.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/dancetravelling.com\\\/#organization\",\"name\":\"Dance Travelling\",\"alternateName\":\"Dance Travelling\",\"url\":\"https:\\\/\\\/dancetravelling.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/dancetravelling.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/dancetravelling.com\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/Captura-de-pantalla-2024-06-11-a-las-18.20.34.png\",\"contentUrl\":\"https:\\\/\\\/dancetravelling.com\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/Captura-de-pantalla-2024-06-11-a-las-18.20.34.png\",\"width\":581,\"height\":226,\"caption\":\"Dance Travelling\"},\"image\":{\"@id\":\"https:\\\/\\\/dancetravelling.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.instagram.com\\\/dancetravelling\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cuba: De La Habana a Santiago - Dance Travelling","description":"Dance Travelling: descubre viajes culturales guiados por la pasi\u00f3n por el baile. Sum\u00e9rgete en ritmos latinos como salsa o bachata, aprende con maestros locales, explora destinos aut\u00e9nticos y vive momentos que mueven el alma.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dancetravelling.com\/it\/cuba-habana-santiago\/","og_locale":"it_IT","og_type":"article","og_title":"Cuba: De La Habana a Santiago - Dance Travelling","og_description":"Dance Travelling: descubre viajes culturales guiados por la pasi\u00f3n por el baile. Sum\u00e9rgete en ritmos latinos como salsa o bachata, aprende con maestros locales, explora destinos aut\u00e9nticos y vive momentos que mueven el alma.","og_url":"https:\/\/dancetravelling.com\/it\/cuba-habana-santiago\/","og_site_name":"Dance Travelling","article_modified_time":"2026-03-26T16:33:05+00:00","og_image":[{"width":1080,"height":721,"url":"https:\/\/dancetravelling.com\/wp-content\/uploads\/2025\/05\/dance-travelling-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"16 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/dancetravelling.com\/cuba-habana-santiago\/","url":"https:\/\/dancetravelling.com\/cuba-habana-santiago\/","name":"Cuba: De La Habana a Santiago - Dance Travelling","isPartOf":{"@id":"https:\/\/dancetravelling.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dancetravelling.com\/cuba-habana-santiago\/#primaryimage"},"image":{"@id":"https:\/\/dancetravelling.com\/cuba-habana-santiago\/#primaryimage"},"thumbnailUrl":"https:\/\/dancetravelling.com\/wp-content\/uploads\/2025\/05\/dance-travelling-1.jpg","datePublished":"2025-05-07T14:17:28+00:00","dateModified":"2026-03-26T16:33:05+00:00","description":"Dance Travelling: descubre viajes culturales guiados por la pasi\u00f3n por el baile. Sum\u00e9rgete en ritmos latinos como salsa o bachata, aprende con maestros locales, explora destinos aut\u00e9nticos y vive momentos que mueven el alma.","breadcrumb":{"@id":"https:\/\/dancetravelling.com\/cuba-habana-santiago\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dancetravelling.com\/cuba-habana-santiago\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/dancetravelling.com\/cuba-habana-santiago\/#primaryimage","url":"https:\/\/dancetravelling.com\/wp-content\/uploads\/2025\/05\/dance-travelling-1.jpg","contentUrl":"https:\/\/dancetravelling.com\/wp-content\/uploads\/2025\/05\/dance-travelling-1.jpg","width":1080,"height":721,"caption":"M\u00fasicos tocando en Santiago: la cuna del son"},{"@type":"BreadcrumbList","@id":"https:\/\/dancetravelling.com\/cuba-habana-santiago\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/dancetravelling.com\/"},{"@type":"ListItem","position":2,"name":"Cuba: De La Habana a Santiago"}]},{"@type":"WebSite","@id":"https:\/\/dancetravelling.com\/#website","url":"https:\/\/dancetravelling.com\/","name":"Danza in viaggio","description":"Balla e viaggia a Cuba","publisher":{"@id":"https:\/\/dancetravelling.com\/#organization"},"alternateName":"Dance Travelling","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dancetravelling.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/dancetravelling.com\/#organization","name":"Danza in viaggio","alternateName":"Dance Travelling","url":"https:\/\/dancetravelling.com\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/dancetravelling.com\/#\/schema\/logo\/image\/","url":"https:\/\/dancetravelling.com\/wp-content\/uploads\/2023\/01\/Captura-de-pantalla-2024-06-11-a-las-18.20.34.png","contentUrl":"https:\/\/dancetravelling.com\/wp-content\/uploads\/2023\/01\/Captura-de-pantalla-2024-06-11-a-las-18.20.34.png","width":581,"height":226,"caption":"Dance Travelling"},"image":{"@id":"https:\/\/dancetravelling.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.instagram.com\/dancetravelling\/"]}]}},"_links":{"self":[{"href":"https:\/\/dancetravelling.com\/it\/wp-json\/wp\/v2\/pages\/1358","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dancetravelling.com\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/dancetravelling.com\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/dancetravelling.com\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dancetravelling.com\/it\/wp-json\/wp\/v2\/comments?post=1358"}],"version-history":[{"count":106,"href":"https:\/\/dancetravelling.com\/it\/wp-json\/wp\/v2\/pages\/1358\/revisions"}],"predecessor-version":[{"id":2856,"href":"https:\/\/dancetravelling.com\/it\/wp-json\/wp\/v2\/pages\/1358\/revisions\/2856"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dancetravelling.com\/it\/wp-json\/wp\/v2\/media\/1428"}],"wp:attachment":[{"href":"https:\/\/dancetravelling.com\/it\/wp-json\/wp\/v2\/media?parent=1358"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}